{"id":7921,"date":"2026-08-25T09:58:31","date_gmt":"2026-08-25T07:58:31","guid":{"rendered":"https:\/\/collections.salvatoreplata.es\/pulso\/"},"modified":"2026-09-02T15:41:18","modified_gmt":"2026-09-02T13:41:18","slug":"pulso","status":"publish","type":"page","link":"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/","title":{"rendered":"Pulso"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:36px;--awb-padding-bottom:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:104%;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:2.5rem;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element\" style=\"text-align:center;--awb-max-width:400px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"433\" height=\"268\" title=\"Pulso\" src=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/Pulso.png\" alt class=\"img-responsive wp-image-7922\" srcset=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/Pulso-200x124.png 200w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/Pulso-400x248.png 400w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/Pulso.png 433w\" sizes=\"(max-width: 640px) 100vw, 433px\" \/><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-background-color:rgba(255,219,219,0);--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:104%;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:2.5rem;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-post-cards fusion-post-cards-1 fusion-grid-archive fusion-grid-columns-4\" style=\"--awb-dots-align:center;--awb-filters-color:var(--awb-color8);--awb-active-filter-border-size:3px;--awb-filters-height:36px;\" data-post-type-label=\"pulso\"><ul class=\"fusion-grid fusion-grid-4 fusion-flex-align-items-flex-start fusion-grid-posts-cards\"><li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:;--awb-flex-shrink-medium:;--awb-flex-grow-small:;--awb-flex-shrink-small:;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1 has-aspect-ratio\" data-layout=\"rollover\" style=\"--awb-crossfade-bg-color:var(--awb-color5);--awb-aspect-ratio:1 \/ 1;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"447\" height=\"447\" src=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-200x200.jpg 200w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-400x400.jpg 400w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer.jpg 447w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 856px) 450px, (min-width: 784px) 600px, (min-width: 712px) 784px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/crown\/\">crown<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer.jpg\" data-options=\"\" data-id=\"5855\" data-rel=\"iLightbox[gallery]\" data-title=\"bamboo-summer\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/crown\/\">\n\t\t\t\t\t\tcrown\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/crown\/\" aria-label=\"crown\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:;--awb-flex-shrink-medium:;--awb-flex-grow-small:;--awb-flex-shrink-small:;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1 has-aspect-ratio\" data-layout=\"rollover\" style=\"--awb-crossfade-bg-color:var(--awb-color5);--awb-aspect-ratio:1 \/ 1;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"447\" height=\"447\" src=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-1-200x200.jpg 200w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-1-400x400.jpg 400w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-1.jpg 447w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 856px) 450px, (min-width: 784px) 600px, (min-width: 712px) 784px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/capri\/\">capri<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-1.jpg\" data-options=\"\" data-id=\"6000\" data-rel=\"iLightbox[gallery]\" data-title=\"capri\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/capri\/\">\n\t\t\t\t\t\tcapri\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/capri\/\" aria-label=\"capri\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:;--awb-flex-shrink-medium:;--awb-flex-grow-small:;--awb-flex-shrink-small:;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1 has-aspect-ratio\" data-layout=\"rollover\" style=\"--awb-crossfade-bg-color:var(--awb-color5);--awb-aspect-ratio:1 \/ 1;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"447\" height=\"447\" src=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-2.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-2-200x200.jpg 200w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-2-400x400.jpg 400w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-2.jpg 447w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 856px) 450px, (min-width: 784px) 600px, (min-width: 712px) 784px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/wedding\/\">wedding<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-2.jpg\" data-options=\"\" data-id=\"5696\" data-rel=\"iLightbox[gallery]\" data-title=\"bamboo-summer-2\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/wedding\/\">\n\t\t\t\t\t\twedding\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/wedding\/\" aria-label=\"wedding\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:;--awb-flex-shrink-medium:;--awb-flex-grow-small:;--awb-flex-shrink-small:;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1 has-aspect-ratio\" data-layout=\"rollover\" style=\"--awb-crossfade-bg-color:var(--awb-color5);--awb-aspect-ratio:1 \/ 1;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"447\" height=\"447\" src=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-3.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"petra\" srcset=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-3-200x200.jpg 200w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-3-400x400.jpg 400w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-3.jpg 447w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 856px) 450px, (min-width: 784px) 600px, (min-width: 712px) 784px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/petra\/\">petra<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-3.jpg\" data-options=\"\" data-id=\"6187\" data-rel=\"iLightbox[gallery]\" data-title=\"petra\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/petra\/\">\n\t\t\t\t\t\tpetra\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/petra\/\" aria-label=\"petra\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:;--awb-flex-shrink-medium:;--awb-flex-grow-small:;--awb-flex-shrink-small:;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1 has-aspect-ratio\" data-layout=\"rollover\" style=\"--awb-crossfade-bg-color:var(--awb-color5);--awb-aspect-ratio:1 \/ 1;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"447\" height=\"447\" src=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-4.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-4-200x200.jpg 200w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-4-400x400.jpg 400w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-4.jpg 447w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 856px) 450px, (min-width: 784px) 600px, (min-width: 712px) 784px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/ninfa\/\">ninfa<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-4.jpg\" data-options=\"\" data-id=\"6085\" data-rel=\"iLightbox[gallery]\" data-title=\"bamboo-summer-4\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/ninfa\/\">\n\t\t\t\t\t\tninfa\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/ninfa\/\" aria-label=\"ninfa\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-7 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:;--awb-flex-shrink-medium:;--awb-flex-grow-small:;--awb-flex-shrink-small:;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1 has-aspect-ratio\" data-layout=\"rollover\" style=\"--awb-crossfade-bg-color:var(--awb-color5);--awb-aspect-ratio:1 \/ 1;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"447\" height=\"447\" src=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-5.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-5-200x200.jpg 200w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-5-400x400.jpg 400w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-5.jpg 447w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 856px) 450px, (min-width: 784px) 600px, (min-width: 712px) 784px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/hoops\/\">hoops<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-5.jpg\" data-options=\"\" data-id=\"6353\" data-rel=\"iLightbox[gallery]\" data-title=\"bamboo-summer-5\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/hoops\/\">\n\t\t\t\t\t\thoops\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/hoops\/\" aria-label=\"hoops\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-8 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:;--awb-flex-shrink-medium:;--awb-flex-grow-small:;--awb-flex-shrink-small:;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1 has-aspect-ratio\" data-layout=\"rollover\" style=\"--awb-crossfade-bg-color:var(--awb-color5);--awb-aspect-ratio:1 \/ 1;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"447\" height=\"447\" src=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-6.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-6-200x200.jpg 200w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-6-400x400.jpg 400w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-6.jpg 447w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 856px) 450px, (min-width: 784px) 600px, (min-width: 712px) 784px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/organic\/\">organic<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-6.jpg\" data-options=\"\" data-id=\"6514\" data-rel=\"iLightbox[gallery]\" data-title=\"organic\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/organic\/\">\n\t\t\t\t\t\torganic\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/organic\/\" aria-label=\"organic\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-9 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:;--awb-flex-shrink-medium:;--awb-flex-grow-small:;--awb-flex-shrink-small:;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1 has-aspect-ratio\" data-layout=\"rollover\" style=\"--awb-crossfade-bg-color:var(--awb-color5);--awb-aspect-ratio:1 \/ 1;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"447\" height=\"447\" src=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-7.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-7-200x200.jpg 200w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-7-400x400.jpg 400w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-7.jpg 447w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 856px) 450px, (min-width: 784px) 600px, (min-width: 712px) 784px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/rainbow\/\">rainbow<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-7.jpg\" data-options=\"\" data-id=\"6631\" data-rel=\"iLightbox[gallery]\" data-title=\"rainbow\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/rainbow\/\">\n\t\t\t\t\t\trainbow\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/rainbow\/\" aria-label=\"rainbow\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-10 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:;--awb-flex-shrink-medium:;--awb-flex-grow-small:;--awb-flex-shrink-small:;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1 has-aspect-ratio\" data-layout=\"rollover\" style=\"--awb-crossfade-bg-color:var(--awb-color5);--awb-aspect-ratio:1 \/ 1;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"447\" height=\"447\" src=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-8.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-8-200x200.jpg 200w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-8-400x400.jpg 400w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-8.jpg 447w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 856px) 450px, (min-width: 784px) 600px, (min-width: 712px) 784px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/vibrant\/\">vibrant<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-8.jpg\" data-options=\"\" data-id=\"6712\" data-rel=\"iLightbox[gallery]\" data-title=\"vibrant\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/vibrant\/\">\n\t\t\t\t\t\tvibrant\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/vibrant\/\" aria-label=\"vibrant\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-11 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:;--awb-flex-shrink-medium:;--awb-flex-grow-small:;--awb-flex-shrink-small:;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1 has-aspect-ratio\" data-layout=\"rollover\" style=\"--awb-crossfade-bg-color:var(--awb-color5);--awb-aspect-ratio:1 \/ 1;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"447\" height=\"447\" src=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-9.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-9-200x200.jpg 200w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-9-400x400.jpg 400w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-9.jpg 447w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 856px) 450px, (min-width: 784px) 600px, (min-width: 712px) 784px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/heritiere\/\">heriti\u00e8re<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-9.jpg\" data-options=\"\" data-id=\"6797\" data-rel=\"iLightbox[gallery]\" data-title=\"bamboo-summer-9\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/heritiere\/\">\n\t\t\t\t\t\theriti\u00e8re\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/heritiere\/\" aria-label=\"heriti\u00e8re\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-12 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:;--awb-flex-shrink-medium:;--awb-flex-grow-small:;--awb-flex-shrink-small:;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1 has-aspect-ratio\" data-layout=\"rollover\" style=\"--awb-crossfade-bg-color:var(--awb-color5);--awb-aspect-ratio:1 \/ 1;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"447\" height=\"447\" src=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-10.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-10-200x200.jpg 200w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-10-400x400.jpg 400w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-10.jpg 447w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 856px) 450px, (min-width: 784px) 600px, (min-width: 712px) 784px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/electra\/\">electra<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-10.jpg\" data-options=\"\" data-id=\"6915\" data-rel=\"iLightbox[gallery]\" data-title=\"bamboo-summer-10\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/electra\/\">\n\t\t\t\t\t\telectra\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/electra\/\" aria-label=\"electra\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-13 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:;--awb-flex-shrink-medium:;--awb-flex-grow-small:;--awb-flex-shrink-small:;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1 has-aspect-ratio\" data-layout=\"rollover\" style=\"--awb-crossfade-bg-color:var(--awb-color5);--awb-aspect-ratio:1 \/ 1;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"447\" height=\"447\" src=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-11.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-11-200x200.jpg 200w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-11-400x400.jpg 400w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-11.jpg 447w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 856px) 450px, (min-width: 784px) 600px, (min-width: 712px) 784px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/aria\/\">aria<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-11.jpg\" data-options=\"\" data-id=\"7012\" data-rel=\"iLightbox[gallery]\" data-title=\"aria\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/aria\/\">\n\t\t\t\t\t\taria\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/aria\/\" aria-label=\"aria\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-14 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:;--awb-flex-shrink-medium:;--awb-flex-grow-small:;--awb-flex-shrink-small:;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1 has-aspect-ratio\" data-layout=\"rollover\" style=\"--awb-crossfade-bg-color:var(--awb-color5);--awb-aspect-ratio:1 \/ 1;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"447\" height=\"447\" src=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-12.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-12-200x200.jpg 200w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-12-400x400.jpg 400w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-12.jpg 447w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 856px) 450px, (min-width: 784px) 600px, (min-width: 712px) 784px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/astral\/\">astral<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-12.jpg\" data-options=\"\" data-id=\"7118\" data-rel=\"iLightbox[gallery]\" data-title=\"astral\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/astral\/\">\n\t\t\t\t\t\tastral\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/astral\/\" aria-label=\"astral\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-15 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:;--awb-flex-shrink-medium:;--awb-flex-grow-small:;--awb-flex-shrink-small:;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1 has-aspect-ratio\" data-layout=\"rollover\" style=\"--awb-crossfade-bg-color:var(--awb-color5);--awb-aspect-ratio:1 \/ 1;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"447\" height=\"447\" src=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-13.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-13-200x200.jpg 200w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-13-400x400.jpg 400w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-13.jpg 447w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 856px) 450px, (min-width: 784px) 600px, (min-width: 712px) 784px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/her\/\">Her<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-13.jpg\" data-options=\"\" data-id=\"7250\" data-rel=\"iLightbox[gallery]\" data-title=\"bamboo-summer-13\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/her\/\">\n\t\t\t\t\t\tHer\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/her\/\" aria-label=\"Her\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-16 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:;--awb-flex-shrink-medium:;--awb-flex-grow-small:;--awb-flex-shrink-small:;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1 has-aspect-ratio\" data-layout=\"rollover\" style=\"--awb-crossfade-bg-color:var(--awb-color5);--awb-aspect-ratio:1 \/ 1;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"447\" height=\"447\" src=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-14.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-14-200x200.jpg 200w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-14-400x400.jpg 400w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-14.jpg 447w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 856px) 450px, (min-width: 784px) 600px, (min-width: 712px) 784px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/silken\/\">silken<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-14.jpg\" data-options=\"\" data-id=\"7312\" data-rel=\"iLightbox[gallery]\" data-title=\"silken\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/silken\/\">\n\t\t\t\t\t\tsilken\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/silken\/\" aria-label=\"silken\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-17 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:;--awb-flex-shrink-medium:;--awb-flex-grow-small:;--awb-flex-shrink-small:;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1 has-aspect-ratio\" data-layout=\"rollover\" style=\"--awb-crossfade-bg-color:var(--awb-color5);--awb-aspect-ratio:1 \/ 1;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"447\" height=\"447\" src=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-15.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-15-200x200.jpg 200w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-15-400x400.jpg 400w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-15.jpg 447w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 856px) 450px, (min-width: 784px) 600px, (min-width: 712px) 784px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/dynasty\/\">dynasty<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-15.jpg\" data-options=\"\" data-id=\"7406\" data-rel=\"iLightbox[gallery]\" data-title=\"dynasty\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/dynasty\/\">\n\t\t\t\t\t\tdynasty\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/dynasty\/\" aria-label=\"dynasty\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-18 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:;--awb-flex-shrink-medium:;--awb-flex-grow-small:;--awb-flex-shrink-small:;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1 has-aspect-ratio\" data-layout=\"rollover\" style=\"--awb-crossfade-bg-color:var(--awb-color5);--awb-aspect-ratio:1 \/ 1;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"447\" height=\"447\" src=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-16.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-16-200x200.jpg 200w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-16-400x400.jpg 400w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-16.jpg 447w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 856px) 450px, (min-width: 784px) 600px, (min-width: 712px) 784px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/bamboo\/\">bamboo<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-16.jpg\" data-options=\"\" data-id=\"7484\" data-rel=\"iLightbox[gallery]\" data-title=\"bamboo\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/bamboo\/\">\n\t\t\t\t\t\tbamboo\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/bamboo\/\" aria-label=\"bamboo\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-19 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:;--awb-flex-shrink-medium:;--awb-flex-grow-small:;--awb-flex-shrink-small:;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1 has-aspect-ratio\" data-layout=\"rollover\" style=\"--awb-crossfade-bg-color:var(--awb-color5);--awb-aspect-ratio:1 \/ 1;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"447\" height=\"447\" src=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-17.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-17-200x200.jpg 200w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-17-400x400.jpg 400w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-17.jpg 447w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 856px) 450px, (min-width: 784px) 600px, (min-width: 712px) 784px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/mystic\/\">mystic<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-17.jpg\" data-options=\"\" data-id=\"7617\" data-rel=\"iLightbox[gallery]\" data-title=\"mystic\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/mystic\/\">\n\t\t\t\t\t\tmystic\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/mystic\/\" aria-label=\"mystic\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-20 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:;--awb-flex-shrink-medium:;--awb-flex-grow-small:;--awb-flex-shrink-small:;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1 has-aspect-ratio\" data-layout=\"rollover\" style=\"--awb-crossfade-bg-color:var(--awb-color5);--awb-aspect-ratio:1 \/ 1;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"447\" height=\"447\" src=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-18.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-18-200x200.jpg 200w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-18-400x400.jpg 400w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-18.jpg 447w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 856px) 450px, (min-width: 784px) 600px, (min-width: 712px) 784px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/valentines\/\">valentines<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-18.jpg\" data-options=\"\" data-id=\"7753\" data-rel=\"iLightbox[gallery]\" data-title=\"valentines\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/valentines\/\">\n\t\t\t\t\t\tvalentines\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/valentines\/\" aria-label=\"valentines\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-21 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:;--awb-flex-shrink-medium:;--awb-flex-grow-small:;--awb-flex-shrink-small:;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1 has-aspect-ratio\" data-layout=\"rollover\" style=\"--awb-crossfade-bg-color:var(--awb-color5);--awb-aspect-ratio:1 \/ 1;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"447\" height=\"447\" src=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-19.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-19-200x200.jpg 200w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-19-400x400.jpg 400w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-19.jpg 447w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 856px) 450px, (min-width: 784px) 600px, (min-width: 712px) 784px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/baby\/\">baby<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/08\/bamboo-summer-19.jpg\" data-options=\"\" data-id=\"7788\" data-rel=\"iLightbox[gallery]\" data-title=\"baby\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/baby\/\">\n\t\t\t\t\t\tbaby\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/collections.salvatoreplata.es\/fr\/pulso\/baby\/\" aria-label=\"baby\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/li>\n<\/ul><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:36px;--awb-padding-bottom:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:104%;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-22 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:2.5rem;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-flex-grow-medium:;--awb-flex-shrink-medium:;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-flex-grow-small:;--awb-flex-shrink-small:;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element\" style=\"text-align:center;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/collections.salvatoreplata.es\/silken-code-summer\/\" target=\"_blank\" aria-label=\"silkencode-winter-banner\" rel=\"noopener noreferrer\"><img decoding=\"async\" width=\"1860\" height=\"433\" src=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/09\/silkencode-winter-banner.jpg\" alt class=\"img-responsive wp-image-7923\" srcset=\"https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/09\/silkencode-winter-banner-200x47.jpg 200w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/09\/silkencode-winter-banner-400x93.jpg 400w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/09\/silkencode-winter-banner-600x140.jpg 600w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/09\/silkencode-winter-banner-800x186.jpg 800w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/09\/silkencode-winter-banner-1200x279.jpg 1200w, https:\/\/collections.salvatoreplata.es\/wp-content\/uploads\/2026\/09\/silkencode-winter-banner.jpg 1860w\" sizes=\"(max-width: 640px) 100vw, 1860px\" \/><\/a><\/span><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"footnotes":""},"class_list":["post-7921","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/collections.salvatoreplata.es\/fr\/wp-json\/wp\/v2\/pages\/7921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collections.salvatoreplata.es\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/collections.salvatoreplata.es\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/collections.salvatoreplata.es\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/collections.salvatoreplata.es\/fr\/wp-json\/wp\/v2\/comments?post=7921"}],"version-history":[{"count":1,"href":"https:\/\/collections.salvatoreplata.es\/fr\/wp-json\/wp\/v2\/pages\/7921\/revisions"}],"predecessor-version":[{"id":7931,"href":"https:\/\/collections.salvatoreplata.es\/fr\/wp-json\/wp\/v2\/pages\/7921\/revisions\/7931"}],"wp:attachment":[{"href":"https:\/\/collections.salvatoreplata.es\/fr\/wp-json\/wp\/v2\/media?parent=7921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}